{"id":4916,"date":"2014-01-22T11:15:45","date_gmt":"2014-01-22T10:15:45","guid":{"rendered":"http:\/\/www.solucominsight.fr\/?p=4916"},"modified":"2014-11-25T11:27:20","modified_gmt":"2014-11-25T10:27:20","slug":"comment-se-positionner-dans-lecosysteme-foisonnant-du-smart","status":"publish","type":"post","link":"https:\/\/www.riskinsight-wavestone.com\/en\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/","title":{"rendered":"Comment se positionner dans l\u2019\u00e9cosyst\u00e8me foisonnant du Smart ?"},"content":{"rendered":"<p align=\"left\">Comme nous l\u2019avons <a title=\"SolucomINSIGHT - Smart\" href=\"http:\/\/www.solucominsight.fr\/?s=smart\" target=\"_blank\">vu pr\u00e9c\u00e9demment<\/a>, l\u2019\u00e9cosyst\u00e8me du Smart est en pleine effervescence. D\u2019un c\u00f4t\u00e9, il y a les secteurs d\u2019activit\u00e9 touch\u00e9s par le Smart (transport, \u00e9nergie, commerce\u2026) et dont les limites sont de plus en plus herm\u00e9tiques entre elles. De l\u2019autre, <strong>la multitude d\u2019acteurs<\/strong> <strong>Smart<\/strong> qui l\u2019animent : ceux du front-office, connus des consommateurs, et ceux du back-office, qui offrent des produits et des services aux acteurs de front-office, avec l\u00e0 encore entre ces deux sous-groupes des fronti\u00e8res qui s\u2019estompent parfois. Comment se rep\u00e9rer dans cet \u00e9cosyst\u00e8me effervescent et en constante \u00e9volution\u00a0? Voici l\u2019une des nombreuses th\u00e9matiques Smart que nous adressons dans notre <a title=\"Synth\u00e8se n\u00b046 : Smart, au-del\u00e0 du buzzword, pr\u00e9parez la transformation !\" href=\"http:\/\/www.solucom.fr\/wp-content\/uploads\/2013\/10\/Synthese_Solucom_Smart_web.pdf\" target=\"_blank\">Synth\u00e8se<\/a>\u00a0\u00e9ponyme, et qui fait en outre l\u2019objet de cette tribune.<\/p>\n<h2 align=\"left\">Un triptyque de sp\u00e9cialistes du Smart<\/h2>\n<h4 align=\"left\">1 &#8211; Les sp\u00e9cialistes de la relation client, agr\u00e9gateurs de services<\/h4>\n<p align=\"left\">Ce sont des acteurs qui connaissent tr\u00e8s bien les clients et leurs comportements de consommation et surtout qui sont consid\u00e9r\u00e9s par les clients comme l\u00e9gitimes pour leur proposer de nouvelles offres, de nouvelles exp\u00e9riences de consommation. On peut dire que ce sont les interlocuteurs clients de \u00ab 1\u00e8re intention \u00bb. \u00a0Leur position peut para\u00eetre simple, mais il n\u2019en est rien car ils doivent :<\/p>\n<ul>\n<li>\u00catre capables d\u2019anticiper les besoins, y compris en se projetant dans de nouveaux domaines de consommation ;<\/li>\n<li>Parvenir \u00e0 offrir une relation simple, fluide quels que soient les canaux, les moments et les motifs de contact ;<\/li>\n<li>Ma\u00eetriser les savoir-faire du m\u00e9tier d\u2019int\u00e9grateur de services qui ne consiste pas \u00e0 additionner des composants, mais \u00e0 co-concevoir avec ses partenaires des services qui prendront leur sens une fois assembl\u00e9s. Cette ing\u00e9nierie de l\u2019assemblage est particuli\u00e8rement d\u00e9licate, le Graal \u00e9tant un v\u00e9ritable saut de valeur.<\/li>\n<\/ul>\n<h4 align=\"left\"><span style=\"font-size: 1em;\">2 &#8211; Les sp\u00e9cialistes de l\u2019innovation : \u00e9quipements, syst\u00e8mes et usages<\/span><\/h4>\n<p align=\"left\">Une grande partie des usages Smart provient d\u2019innovations valorisant des technologies existantes en les associant et en inventant un usage, c\u2019est-\u00e0-dire un r\u00e9sultat utile pour un client. Bien s\u00fbr, les structures de recherche et d\u00e9veloppement des grands groupes consacrent des ressources importantes \u00e0 cette recherche, mais force est de constater que le foisonnement de l\u2019innovation est presque infini chez les petits acteurs et que de nombreux usages ou \u00ab briques de services \u00bb Smart ont \u00e9t\u00e9 d\u00e9velopp\u00e9s par ces entreprises fonctionnant sur une logique de start-up, comme par exemple <a title=\"AlertMe\" href=\"https:\/\/www.alertme.com\/\" target=\"_blank\">AlertMe<\/a>.<\/p>\n<p align=\"left\">Pour ces acteurs, il ne s\u2019agit pas simplement de surfer sur les technologies, il s\u2019agit d\u2019abord de trouver de nouveaux usages et de convaincre des clients ou des partenaires de les tester et de les d\u00e9velopper\u2026 pour les imposer dans le paysage. Ils doivent donc \u00e0 la fois bien conna\u00eetre les clients pour raisonner usage et conduire une strat\u00e9gie partenariale tr\u00e8s forte. Innovation client et strat\u00e9gie partenariale sont les deux imp\u00e9ratifs majeurs pour que ces acteurs restent durablement autonomes. Cependant, dans la pratique, bien souvent, ils sont rachet\u00e9s par des grands groupes agissant dans leur secteur majeur d\u2019activit\u00e9.<\/p>\n<h4 align=\"left\">3 &#8211; Les sp\u00e9cialistes des infrastructures et services critiques (back-office) indispensables au bon fonctionnement de l\u2019ensemble de l\u2019\u00e9cosyst\u00e8me Smart<\/h4>\n<p align=\"left\">L\u2019exemple d\u2019Atos (<a title=\"Synth\u00e8se n\u00b046 : Smart, au-del\u00e0 du buzzword, pr\u00e9parez la transformation !\" href=\"http:\/\/www.solucom.fr\/wp-content\/uploads\/2013\/10\/Synthese_Solucom_Smart_web.pdf\" target=\"_blank\">voir notre Synth\u00e8se Smart page 10<\/a>)\u00a0montre que la strat\u00e9gie de sp\u00e9cialisation back-office est tout \u00e0 fait centrale dans l\u2019univers du Smart. Il s\u2019agit d\u2019abord de la gestion des donn\u00e9es <a title=\"SolucomINSIGHT - dossier Big data\" href=\"http:\/\/www.solucominsight.fr\/category\/dossiers\/big-data-dossiers\/\" target=\"_blank\">Big data<\/a>, mais aussi de composants plus \u00e9l\u00e9mentaires d\u2019\u00e9quipements communicants comme les cartes SIM. Il y a en France aujourd\u2019hui plus de cartes SIM que d\u2019habitants, puisqu\u2019au-del\u00e0 des t\u00e9l\u00e9phones, elles \u00e9quipent par exemple les tablettes et les automobiles. Les sp\u00e9cialistes du back-office doivent \u00e0 la fois industrialiser leurs offres et co-concevoir les services du futur avec leurs partenaires, en particulier les acteurs du front-office\u2026 sans compter qu\u2019ils doivent promouvoir et imposer leurs standards pour devenir, effectivement, incontournables.<\/p>\n<h2 align=\"left\">Une \u00e9volution dynamique des positionnements<\/h2>\n<p align=\"left\">Le positionnement ne se limite ni aux trois r\u00f4les types pr\u00e9sent\u00e9s ci-avant, ni \u00e0 une vision statique. Si l\u2019on s\u2019int\u00e9resse maintenant aux dynamiques, on peut sch\u00e9matiquement distinguer quatre grands types de mouvements.<\/p>\n<h4 align=\"left\">1 &#8211; L\u2019\u00e9mergence<\/h4>\n<p align=\"left\">On pense bien s\u00fbr aux start-up, mais cela peut aussi concerner le lancement de nouvelles activit\u00e9s dans des entreprises install\u00e9es. Les enjeux sont multiples : pertinence de l\u2019offre, acc\u00e8s aux clients, rentabilit\u00e9 du mod\u00e8le \u00e9conomique, strat\u00e9gie de d\u00e9veloppement ou de valorisation capitalistique.<\/p>\n<h4 align=\"left\">2 &#8211; Le d\u00e9placement centrip\u00e8te<\/h4>\n<p align=\"left\">Des acteurs du back-office se diversifient ou se transforment en acteurs du front-office. C\u2019est une strat\u00e9gie fondamentale du secteur industriel europ\u00e9en depuis de nombreuses ann\u00e9es : cr\u00e9er de la valeur par une offre combinant produits et services avec en cible une facturation au r\u00e9sultat. De nombreuses entreprises suivent cette strat\u00e9gie, comme Schneider Electric qui d\u00e9veloppe des offres de prise en charge de la performance \u00e9nerg\u00e9tique des clients. Ce mouvement se traduit par un fort enjeu de d\u00e9veloppement de la \u00ab culture services \u00bb.<\/p>\n<h4 align=\"left\">3 &#8211; Le d\u00e9placement centrifuge<\/h4>\n<p align=\"left\">Ce mouvement est plus rare, il est cependant cl\u00e9 dans l\u2019univers du Smart o\u00f9 le back-office joue un r\u00f4le central. C\u2019est aussi, pour les start-up innovantes, un moyen pour trouver des gisements de croissance en adoptant une strat\u00e9gie de d\u00e9veloppement en \u00ab marque blanche \u00bb (cf. le cas d\u2019<a title=\"Synth\u00e8se n\u00b046 : Smart, au-del\u00e0 du buzzword, pr\u00e9parez la transformation !\" href=\"http:\/\/www.solucom.fr\/wp-content\/uploads\/2013\/10\/Synthese_Solucom_Smart_web.pdf\" target=\"_blank\">AlertMe en page 10 de la Synth\u00e8se<\/a>).<\/p>\n<h4 align=\"left\">4 &#8211; L\u2019extension circulaire<\/h4>\n<p align=\"left\">L\u2019int\u00e9r\u00eat d\u2019une vision multisectorielle du Smart, c\u2019est qu\u2019elle fait appara\u00eetre le potentiel de ce type de mouvement. Il peut concerner tout type d\u2019acteurs :<\/p>\n<ul>\n<li>D\u2019abord, bien s\u00fbr, les sp\u00e9cialistes des infrastructures, puisqu\u2019en g\u00e9n\u00e9ral celles-ci peuvent \u00eatre utilis\u00e9es pour tous les types d\u2019usage ;<\/li>\n<li>Les sp\u00e9cialistes de la relation client et de l\u2019int\u00e9gration de services ensuite, qui doivent sans cesse renforcer leur l\u00e9gitimit\u00e9 en cherchant \u00e0 couvrir le plus largement possible les besoins des clients avec des acc\u00e8s et des services ergonomiques et simples ;<\/li>\n<li>Les sp\u00e9cialistes de l\u2019innovation, mais cela s\u2019av\u00e8re plus difficile parce que cela suppose une aptitude \u00e0 se projeter dans des univers d\u2019usages tr\u00e8s diff\u00e9rents.<\/li>\n<\/ul>\n<p align=\"left\">Tous ces mouvements sont \u00e0 la fois des opportunit\u00e9s de d\u00e9veloppement ou des menaces concurrentielles. \u00c0 tout moment, de nouveaux acteurs peuvent appara\u00eetre dans son propre champ concurrentiel. Il faut donc y \u00eatre tr\u00e8s attentif.<\/p>\n<h2 align=\"left\">Pas de Smart sans cadre r\u00e9glementaire<\/h2>\n<p align=\"left\">Bien s\u00fbr, les innovations technologiques et les innovations d\u2019usages sont deux moteurs fondamentaux du <em>Smart<\/em>, mais ces innovations ont besoin d\u2019un terreau favorable pour se d\u00e9velopper. Ce terreau ne correspond ni \u00e0 la demande spontan\u00e9e des clients ni \u00e0 la rentabilit\u00e9 intrins\u00e8que des offres.<\/p>\n<p align=\"left\">C\u2019est le cadre r\u00e9glementaire qui appara\u00eet comme \u00e9tant le socle de d\u00e9veloppement du Smart. Par exemple dans le secteur du b\u00e2timent, la r\u00e9glementation thermique (aujourd\u2019hui la RT 2012) joue un r\u00f4le central pour l\u2019installation de solutions intelligentes de pilotage des consommations \u00e9nerg\u00e9tiques. Les pouvoirs publics ont donc une responsabilit\u00e9 essentielle pour \u00ab\u00a0cr\u00e9er \u00bb les territoires du Smart : \u00ab les collectivit\u00e9s locales sont \u00e0 la Smart city ce que Apple est au smartphone. \u00bb. Ainsi, le v\u00e9hicule \u00e9lectrique ne se d\u00e9veloppera que lorsque les pouvoirs publics fixeront les r\u00e8gles et les aides qui permettront de cr\u00e9er une infrastructure de recharge : par exemple permettre \u00e0 un copropri\u00e9taire d\u2019installer une prise sur son emplacement de stationnement sans avoir besoin d\u2019obtenir la majorit\u00e9 en assembl\u00e9e g\u00e9n\u00e9rale.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme nous l\u2019avons vu pr\u00e9c\u00e9demment, l\u2019\u00e9cosyst\u00e8me du Smart est en pleine effervescence. D\u2019un c\u00f4t\u00e9, il y a les secteurs d\u2019activit\u00e9 touch\u00e9s par le Smart (transport, \u00e9nergie, commerce\u2026) et dont les limites sont de plus en plus herm\u00e9tiques entre elles. De&#8230;<\/p>\n","protected":false},"author":48,"featured_media":6039,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"page-templates\/tmpl-one.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[40,34],"tags":[1509,1508,95],"coauthors":[830],"class_list":["post-4916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energie-utilities","category-strategie-d-entreprise","tag-acteurs-back-office","tag-acteurs-front-office","tag-innovation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment se positionner dans l\u2019\u00e9cosyst\u00e8me foisonnant du Smart ?<\/title>\n<meta name=\"description\" content=\"Comme nous l\u2019avons vu pr\u00e9c\u00e9demment, l\u2019\u00e9cosyst\u00e8me du Smart est en pleine effervescence. D\u2019un c\u00f4t\u00e9, il y a les secteurs d\u2019activit\u00e9 touch\u00e9s par le Smart (transport, \u00e9nergie, commerce\u2026) et dont les limites sont de plus en plus herm\u00e9tiques entre elles. De l\u2019autre, la multitude d\u2019acteurs Smart qui l\u2019animent: ceux du front-office, connus des consommateurs, et ceux du back-office, qui offrent des produits et des services aux acteurs de front-office, avec l\u00e0 encore entre ces deux sous-groupes des fronti\u00e8res qui s\u2019estompent parfois. Comment se rep\u00e9rer dans cet \u00e9cosyst\u00e8me effervescent et en constante \u00e9volution ? Voici l\u2019une des nombreuses th\u00e9matiques Smart que nous adressons dans notre Synth\u00e8se \u00e9ponyme, et qui fait en outre l\u2019objet de cette tribune.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment se positionner dans l\u2019\u00e9cosyst\u00e8me foisonnant du Smart ?\" \/>\n<meta property=\"og:description\" content=\"Comme nous l\u2019avons vu pr\u00e9c\u00e9demment, l\u2019\u00e9cosyst\u00e8me du Smart est en pleine effervescence. D\u2019un c\u00f4t\u00e9, il y a les secteurs d\u2019activit\u00e9 touch\u00e9s par le Smart (transport, \u00e9nergie, commerce\u2026) et dont les limites sont de plus en plus herm\u00e9tiques entre elles. De l\u2019autre, la multitude d\u2019acteurs Smart qui l\u2019animent: ceux du front-office, connus des consommateurs, et ceux du back-office, qui offrent des produits et des services aux acteurs de front-office, avec l\u00e0 encore entre ces deux sous-groupes des fronti\u00e8res qui s\u2019estompent parfois. Comment se rep\u00e9rer dans cet \u00e9cosyst\u00e8me effervescent et en constante \u00e9volution ? Voici l\u2019une des nombreuses th\u00e9matiques Smart que nous adressons dans notre Synth\u00e8se \u00e9ponyme, et qui fait en outre l\u2019objet de cette tribune.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/\" \/>\n<meta property=\"og:site_name\" content=\"RiskInsight\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-22T10:15:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-11-25T10:27:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/11\/Fotolia_55449785_Business-chalk-sketch_\u00a9-Sergey-Nivens-573.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"573\" \/>\n\t<meta property=\"og:image:height\" content=\"217\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Damien Mermet\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Mermet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/\"},\"author\":{\"name\":\"Damien Mermet\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/person\/16cda089ab49592ae03fa446c8cf92f3\"},\"headline\":\"Comment se positionner dans l\u2019\u00e9cosyst\u00e8me foisonnant du Smart ?\",\"datePublished\":\"2014-01-22T10:15:45+00:00\",\"dateModified\":\"2014-11-25T10:27:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/\"},\"wordCount\":1304,\"publisher\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/11\/Fotolia_55449785_Business-chalk-sketch_\u00a9-Sergey-Nivens-573.jpg\",\"keywords\":[\"acteurs back-office\",\"acteurs front-office\",\"Innovation\"],\"articleSection\":[\"M\u00e9tiers - Energie\",\"M\u00e9tiers - Strat\u00e9gie d\u2019entreprise\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/\",\"url\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/\",\"name\":\"Comment se positionner dans l\u2019\u00e9cosyst\u00e8me foisonnant du Smart ?\",\"isPartOf\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/11\/Fotolia_55449785_Business-chalk-sketch_\u00a9-Sergey-Nivens-573.jpg\",\"datePublished\":\"2014-01-22T10:15:45+00:00\",\"dateModified\":\"2014-11-25T10:27:20+00:00\",\"description\":\"Comme nous l\u2019avons vu pr\u00e9c\u00e9demment, l\u2019\u00e9cosyst\u00e8me du Smart est en pleine effervescence. D\u2019un c\u00f4t\u00e9, il y a les secteurs d\u2019activit\u00e9 touch\u00e9s par le Smart (transport, \u00e9nergie, commerce\u2026) et dont les limites sont de plus en plus herm\u00e9tiques entre elles. De l\u2019autre, la multitude d\u2019acteurs Smart qui l\u2019animent: ceux du front-office, connus des consommateurs, et ceux du back-office, qui offrent des produits et des services aux acteurs de front-office, avec l\u00e0 encore entre ces deux sous-groupes des fronti\u00e8res qui s\u2019estompent parfois. Comment se rep\u00e9rer dans cet \u00e9cosyst\u00e8me effervescent et en constante \u00e9volution ? Voici l\u2019une des nombreuses th\u00e9matiques Smart que nous adressons dans notre Synth\u00e8se \u00e9ponyme, et qui fait en outre l\u2019objet de cette tribune.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#primaryimage\",\"url\":\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/11\/Fotolia_55449785_Business-chalk-sketch_\u00a9-Sergey-Nivens-573.jpg\",\"contentUrl\":\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/11\/Fotolia_55449785_Business-chalk-sketch_\u00a9-Sergey-Nivens-573.jpg\",\"width\":573,\"height\":217},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.riskinsight-wavestone.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment se positionner dans l\u2019\u00e9cosyst\u00e8me foisonnant du Smart ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#website\",\"url\":\"https:\/\/www.riskinsight-wavestone.com\/en\/\",\"name\":\"RiskInsight\",\"description\":\"The cybersecurity &amp; digital trust blog by Wavestone&#039;s consultants\",\"publisher\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.riskinsight-wavestone.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#organization\",\"name\":\"Wavestone\",\"url\":\"https:\/\/www.riskinsight-wavestone.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2021\/08\/Monogramme\u2013W\u2013NEGA-RGB-50x50-1.png\",\"contentUrl\":\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2021\/08\/Monogramme\u2013W\u2013NEGA-RGB-50x50-1.png\",\"width\":50,\"height\":50,\"caption\":\"Wavestone\"},\"image\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/person\/16cda089ab49592ae03fa446c8cf92f3\",\"name\":\"Damien Mermet\",\"url\":\"https:\/\/www.riskinsight-wavestone.com\/en\/author\/damien-mermet\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment se positionner dans l\u2019\u00e9cosyst\u00e8me foisonnant du Smart ?","description":"Comme nous l\u2019avons vu pr\u00e9c\u00e9demment, l\u2019\u00e9cosyst\u00e8me du Smart est en pleine effervescence. D\u2019un c\u00f4t\u00e9, il y a les secteurs d\u2019activit\u00e9 touch\u00e9s par le Smart (transport, \u00e9nergie, commerce\u2026) et dont les limites sont de plus en plus herm\u00e9tiques entre elles. De l\u2019autre, la multitude d\u2019acteurs Smart qui l\u2019animent: ceux du front-office, connus des consommateurs, et ceux du back-office, qui offrent des produits et des services aux acteurs de front-office, avec l\u00e0 encore entre ces deux sous-groupes des fronti\u00e8res qui s\u2019estompent parfois. Comment se rep\u00e9rer dans cet \u00e9cosyst\u00e8me effervescent et en constante \u00e9volution ? Voici l\u2019une des nombreuses th\u00e9matiques Smart que nous adressons dans notre Synth\u00e8se \u00e9ponyme, et qui fait en outre l\u2019objet de cette tribune.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/","og_locale":"en_US","og_type":"article","og_title":"Comment se positionner dans l\u2019\u00e9cosyst\u00e8me foisonnant du Smart ?","og_description":"Comme nous l\u2019avons vu pr\u00e9c\u00e9demment, l\u2019\u00e9cosyst\u00e8me du Smart est en pleine effervescence. D\u2019un c\u00f4t\u00e9, il y a les secteurs d\u2019activit\u00e9 touch\u00e9s par le Smart (transport, \u00e9nergie, commerce\u2026) et dont les limites sont de plus en plus herm\u00e9tiques entre elles. De l\u2019autre, la multitude d\u2019acteurs Smart qui l\u2019animent: ceux du front-office, connus des consommateurs, et ceux du back-office, qui offrent des produits et des services aux acteurs de front-office, avec l\u00e0 encore entre ces deux sous-groupes des fronti\u00e8res qui s\u2019estompent parfois. Comment se rep\u00e9rer dans cet \u00e9cosyst\u00e8me effervescent et en constante \u00e9volution ? Voici l\u2019une des nombreuses th\u00e9matiques Smart que nous adressons dans notre Synth\u00e8se \u00e9ponyme, et qui fait en outre l\u2019objet de cette tribune.","og_url":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/","og_site_name":"RiskInsight","article_published_time":"2014-01-22T10:15:45+00:00","article_modified_time":"2014-11-25T10:27:20+00:00","og_image":[{"width":573,"height":217,"url":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/11\/Fotolia_55449785_Business-chalk-sketch_\u00a9-Sergey-Nivens-573.jpg","type":"image\/jpeg"}],"author":"Damien Mermet","twitter_misc":{"Written by":"Damien Mermet","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#article","isPartOf":{"@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/"},"author":{"name":"Damien Mermet","@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/person\/16cda089ab49592ae03fa446c8cf92f3"},"headline":"Comment se positionner dans l\u2019\u00e9cosyst\u00e8me foisonnant du Smart ?","datePublished":"2014-01-22T10:15:45+00:00","dateModified":"2014-11-25T10:27:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/"},"wordCount":1304,"publisher":{"@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#organization"},"image":{"@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#primaryimage"},"thumbnailUrl":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/11\/Fotolia_55449785_Business-chalk-sketch_\u00a9-Sergey-Nivens-573.jpg","keywords":["acteurs back-office","acteurs front-office","Innovation"],"articleSection":["M\u00e9tiers - Energie","M\u00e9tiers - Strat\u00e9gie d\u2019entreprise"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/","url":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/","name":"Comment se positionner dans l\u2019\u00e9cosyst\u00e8me foisonnant du Smart ?","isPartOf":{"@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#primaryimage"},"image":{"@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#primaryimage"},"thumbnailUrl":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/11\/Fotolia_55449785_Business-chalk-sketch_\u00a9-Sergey-Nivens-573.jpg","datePublished":"2014-01-22T10:15:45+00:00","dateModified":"2014-11-25T10:27:20+00:00","description":"Comme nous l\u2019avons vu pr\u00e9c\u00e9demment, l\u2019\u00e9cosyst\u00e8me du Smart est en pleine effervescence. D\u2019un c\u00f4t\u00e9, il y a les secteurs d\u2019activit\u00e9 touch\u00e9s par le Smart (transport, \u00e9nergie, commerce\u2026) et dont les limites sont de plus en plus herm\u00e9tiques entre elles. De l\u2019autre, la multitude d\u2019acteurs Smart qui l\u2019animent: ceux du front-office, connus des consommateurs, et ceux du back-office, qui offrent des produits et des services aux acteurs de front-office, avec l\u00e0 encore entre ces deux sous-groupes des fronti\u00e8res qui s\u2019estompent parfois. Comment se rep\u00e9rer dans cet \u00e9cosyst\u00e8me effervescent et en constante \u00e9volution ? Voici l\u2019une des nombreuses th\u00e9matiques Smart que nous adressons dans notre Synth\u00e8se \u00e9ponyme, et qui fait en outre l\u2019objet de cette tribune.","breadcrumb":{"@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#primaryimage","url":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/11\/Fotolia_55449785_Business-chalk-sketch_\u00a9-Sergey-Nivens-573.jpg","contentUrl":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/11\/Fotolia_55449785_Business-chalk-sketch_\u00a9-Sergey-Nivens-573.jpg","width":573,"height":217},{"@type":"BreadcrumbList","@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/01\/comment-se-positionner-dans-lecosysteme-foisonnant-du-smart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.riskinsight-wavestone.com\/en\/"},{"@type":"ListItem","position":2,"name":"Comment se positionner dans l\u2019\u00e9cosyst\u00e8me foisonnant du Smart ?"}]},{"@type":"WebSite","@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#website","url":"https:\/\/www.riskinsight-wavestone.com\/en\/","name":"RiskInsight","description":"The cybersecurity &amp; digital trust blog by Wavestone&#039;s consultants","publisher":{"@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.riskinsight-wavestone.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#organization","name":"Wavestone","url":"https:\/\/www.riskinsight-wavestone.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2021\/08\/Monogramme\u2013W\u2013NEGA-RGB-50x50-1.png","contentUrl":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2021\/08\/Monogramme\u2013W\u2013NEGA-RGB-50x50-1.png","width":50,"height":50,"caption":"Wavestone"},"image":{"@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/person\/16cda089ab49592ae03fa446c8cf92f3","name":"Damien Mermet","url":"https:\/\/www.riskinsight-wavestone.com\/en\/author\/damien-mermet\/"}]}},"_links":{"self":[{"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/posts\/4916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/comments?post=4916"}],"version-history":[{"count":10,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/posts\/4916\/revisions"}],"predecessor-version":[{"id":6194,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/posts\/4916\/revisions\/6194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/media\/6039"}],"wp:attachment":[{"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/media?parent=4916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/categories?post=4916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/tags?post=4916"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/coauthors?post=4916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}