{"id":5074,"date":"2014-02-19T07:49:29","date_gmt":"2014-02-19T06:49:29","guid":{"rendered":"http:\/\/www.solucominsight.fr\/?p=5074"},"modified":"2015-01-21T09:52:57","modified_gmt":"2015-01-21T08:52:57","slug":"comment-reussir-un-transfert-dactivite-dans-votre-entreprise","status":"publish","type":"post","link":"https:\/\/www.riskinsight-wavestone.com\/en\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/","title":{"rendered":"Comment r\u00e9ussir un transfert d\u2019activit\u00e9 dans votre entreprise ?"},"content":{"rendered":"<p><em>Un transfert d\u2019activit\u00e9 d\u2019une \u00e9quipe \u00e0 une autre est souvent chronophage et long \u00e0 mettre en place\u2026 beaucoup trop en tous cas au regard des objectifs que s\u2019est fix\u00e9e l\u2019entreprise\u00a0! Clarifier la r\u00e9partition des activit\u00e9s et responsabilit\u00e9s entre directions ou encore\u00a0 homog\u00e9n\u00e9iser et industrialiser les pratiques : les attentes de performance rencontrent facilement des freins manag\u00e9riaux (transfert de responsabilit\u00e9, d\u2019\u00e9quipe et \/ ou de budget) et individuels (transfert d\u2019\u00e9quipe, \u00e9volution du p\u00e9rim\u00e8tre d\u2019activit\u00e9, de la posture voire des outils). Comment alors atteindre les objectifs initiaux\u00a0? Quels dispositifs mettre en place pour en ma\u00eetriser le rythme de mise en \u0153uvre et ne pas bloquer la fluidit\u00e9 de fonctionnement\u00a0?<\/em><\/p>\n<h2>Piloter le transfert d\u2019activit\u00e9<\/h2>\n<p>Que le transfert d\u2019activit\u00e9 rel\u00e8ve d\u2019une r\u00e9organisation entre deux entit\u00e9s d\u2019une m\u00eame entreprise ou d\u2019un projet d\u2019externalisation, ce dernier se pilote. Il doit \u00eatre consid\u00e9r\u00e9 comme un projet \u00e0 part enti\u00e8re, avec toutes ses composantes\u00a0habituelles : une cible (clairement d\u00e9finie et d\u00e9clin\u00e9e op\u00e9rationnellement), une trajectoire de mise en \u0153uvre (avec des paliers distincts \u00e0 franchir, pour donner le rythme) sans oublier des indicateurs restreints, pr\u00e9alablement d\u00e9finis et choisis avec attention (ces derniers doivent \u00eatre pertinents et f\u00e9d\u00e9rateurs, couvrir aussi bien l\u2019avancement de la mise en \u0153uvre que l\u2019impact sur les r\u00e9sultats op\u00e9rationnels). Il sera enfin cl\u00e9 de d\u00e9terminer un nom au projet\u2026 et d\u2019y associer un chef de projet op\u00e9rationnel officiellement nomm\u00e9 et clairement objectiv\u00e9.<\/p>\n<h2>Rendre le management acteur du transfert d\u2019activit\u00e9<\/h2>\n<p>Sans attendre, les dirigeants doivent embarquer la ligne manag\u00e9riale. Partager la n\u00e9cessit\u00e9 de ce changement, leur dire ce qu\u2019on attend d\u2019eux concr\u00e8tement, co-construire la cible et la trajectoire, et prendre en compte les points d\u2019attention op\u00e9rationnels : tout ceci constitue le point de d\u00e9part. Leur assurer une communication r\u00e9guli\u00e8re et \u00ab\u00a0en exclusivit\u00e9\u00a0\u00bb est \u00e9galement cl\u00e9. Mais cela ne suffira pas.<\/p>\n<p>Pour \u00eatre pleinement actrice du changement, la ligne manag\u00e9riale va devoir prendre une nouvelle posture, affirm\u00e9e et volontaire. Plus encore, elle doit \u00eatre pleinement responsabilis\u00e9e\u00a0: avoir des objectifs clairs \u00e0 atteindre, les marges de man\u0153uvre n\u00e9cessaires \u00e0 l\u2019atteinte de ces objectifs, des outils pour piloter l\u2019activit\u00e9 mais \u00e9galement pour d\u00e9multiplier les informations et d\u00e9cisions. Dernier ingr\u00e9dient crucial de cette recette de la r\u00e9ussite\u00a0: elle doit avoir la garantie d\u2019\u00eatre \u00e9cout\u00e9e par la hi\u00e9rarchie.<\/p>\n<h2>Outiller le processus de mise en \u0153uvre<\/h2>\n<p>Au-del\u00e0 de l\u2019incontournable <strong>process de transfert<\/strong>, quatre outils permettent de bien accompagner les \u00e9quipes op\u00e9rationnelles pour s\u00e9curiser la mise en \u0153uvre\u00a0:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>Des grilles d\u2019activit\u00e9<\/strong>, recensant les activit\u00e9s et listant celles \u00e0 transf\u00e9rer\u00a0;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Un <strong>plan de transfert\u00a0 type<\/strong> : pour chaque activit\u00e9 transf\u00e9r\u00e9e, des modalit\u00e9s, des acteurs et des \u00e9ch\u00e9ances clairement formalis\u00e9s\u00a0;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Une <strong><em>checklist<\/em> de bascule<\/strong> pour go \/ no go : un transfert d\u2019activit\u00e9 peut impliquer des changements de droits et d\u2019habilitations, une communication sp\u00e9cifique \u00e0 d\u2019\u00e9ventuels utilisateurs ou clients\u2026 tous ces impacts devront \u00eatre anticip\u00e9s et les actions de pr\u00e9paration associ\u00e9es inscrites dans le cadre d\u2019un retroplanning partag\u00e9\u00a0;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>Des fiches de r\u00f4les<\/strong>, aussi bien pour les entit\u00e9s c\u00e9dantes que prenantes\u00a0! En p\u00e9riode de changement, chacun a besoin de voir clarifier son domaine de responsabilit\u00e9, ses activit\u00e9s et la posture qu\u2019il doit adopter.<\/p>\n<h2>Ancrer le changement<\/h2>\n<p><strong>Communication et conduite du changement<\/strong> sont des axes \u00e0 part enti\u00e8re de pilotage d\u2019un projet de transfert d\u2019activit\u00e9. Des plans doivent donc \u00eatre d\u00e9finis en amont et ajust\u00e9s au fil des \u00e9v\u00e9nements, en lien avec chaque direction concern\u00e9e et avec l\u2019appui des RH.<\/p>\n<p>Tout l\u2019enjeu est d\u2019ancrer le changement sur le terrain. Pouvoir conna\u00eetre et traiter les points de blocage op\u00e9rationnels et les tentations de \u00ab\u00a0faire comme avant\u00a0\u00bb est donc cl\u00e9. Il faut donc se contraindre \u00e0 r\u00e9unir r\u00e9guli\u00e8rement les acteurs op\u00e9rationnels sur un cr\u00e9neau court pour partager les difficult\u00e9s et les bonnes pratiques (physiquement ou en audioconf\u00e9rence). Par ailleurs, il est n\u00e9cessaire de permettre \u00e0 chacun de poser ses questions en ouvrant des lieux d\u00e9di\u00e9s (rencontre physique sur des horaires sp\u00e9cifiques, FAQ en ligne sur l\u2019intranet ou le r\u00e9seau social d\u2019entreprise\u2026)\u2026 et d\u2019acc\u00e9der aux r\u00e9ponses apport\u00e9es aux autres.<\/p>\n<p>Une chose est s\u00fbre, cette conduite de changement devra continuer dans le temps, apr\u00e8s la fin m\u00eame du projet. Ce serait une erreur de s\u2019attendre \u00e0 ce que le changement, pilot\u00e9 et anim\u00e9 pendant la p\u00e9riode projet, soit derri\u00e8re vous \u00e0 sa fin. \u00c9tape souvent n\u00e9glig\u00e9e, les modalit\u00e9s de suivi en conditions op\u00e9rationnelles doivent \u00eatre d\u00e9finies, valid\u00e9es et communiqu\u00e9es avant la fin de projet.<\/p>\n<h2>Un transfert d\u2019activit\u00e9 est un projet de transformation \u00e0 part enti\u00e8re<\/h2>\n<p>Bouleversement des \u00e9quipes et temps n\u00e9cessaire au changement ne doivent pas \u00eatre sous-estim\u00e9s. Un transfert d\u2019activit\u00e9 peut n\u00e9cessiter 6 \u00e0 18 mois de travaux selon les contraintes op\u00e9rationnelles, les moyens accord\u00e9s et le niveau de r\u00e9sistance rencontr\u00e9. Des temps significatifs seront n\u00e9cessaires pour permettre aux managers et \u00e0 leurs \u00e9quipes de relever ce d\u00e9fi.\u00a0 Autant d\u2019\u00e9l\u00e9ments \u00e0 \u00e9valuer en amont du projet, et qui devront \u00eatre officialis\u00e9s et pilot\u00e9s. Il est ainsi n\u00e9cessaire de savoir actionner les bons leviers et d\u2019\u00eatre \u00e0 l\u2019\u00e9coute de tous, de bout en bout du projet.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.solucominsight.fr\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/transfert-d-activite\/\" rel=\"attachment wp-att-5078\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-5078\" title=\"transfert d activite\" src=\"http:\/\/www.solucominsight.fr\/wp-content\/uploads\/2014\/02\/transfert-d-activite.png\" alt=\"\" width=\"568\" height=\"383\" srcset=\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/transfert-d-activite.png 1353w, https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/transfert-d-activite-284x191.png 284w, https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/transfert-d-activite-58x39.png 58w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un transfert d\u2019activit\u00e9 d\u2019une \u00e9quipe \u00e0 une autre est souvent chronophage et long \u00e0 mettre en place\u2026 beaucoup trop en tous cas au regard des objectifs que s\u2019est fix\u00e9e l\u2019entreprise\u00a0! Clarifier la r\u00e9partition des activit\u00e9s et responsabilit\u00e9s entre directions ou&#8230;<\/p>\n","protected":false},"author":111,"featured_media":6185,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"page-templates\/tmpl-one.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[35],"tags":[257,1546,1545,142],"coauthors":[953,1544],"class_list":["post-5074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-strategie-projets-it","tag-conduite-du-changement","tag-reorganisation","tag-transfert-dactivite","tag-transformation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment r\u00e9ussir un transfert d\u2019activit\u00e9 dans votre entreprise ?<\/title>\n<meta name=\"description\" content=\"Un transfert d\u2019activit\u00e9 d\u2019une \u00e9quipe \u00e0 une autre est souvent chronophage et long \u00e0 mettre en place\u2026 beaucoup trop en tous cas au regard des objectifs que s\u2019est fix\u00e9e l\u2019entreprise ! Clarifier la r\u00e9partition des activit\u00e9s et responsabilit\u00e9s entre directions ou encore homog\u00e9n\u00e9iser et industrialiser les pratiques\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment r\u00e9ussir un transfert d\u2019activit\u00e9 dans votre entreprise ?\" \/>\n<meta property=\"og:description\" content=\"Un transfert d\u2019activit\u00e9 d\u2019une \u00e9quipe \u00e0 une autre est souvent chronophage et long \u00e0 mettre en place\u2026 beaucoup trop en tous cas au regard des objectifs que s\u2019est fix\u00e9e l\u2019entreprise ! Clarifier la r\u00e9partition des activit\u00e9s et responsabilit\u00e9s entre directions ou encore homog\u00e9n\u00e9iser et industrialiser les pratiques\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/\" \/>\n<meta property=\"og:site_name\" content=\"RiskInsight\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-19T06:49:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-21T08:52:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/tourbillon_11266243m-credit-principal-fotolia.com1_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1194\" \/>\n\t<meta property=\"og:image:height\" content=\"1592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emilie Molino, Carole Pezzali\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emilie Molino, Carole Pezzali\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/\"},\"author\":{\"name\":\"Emilie Molino\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/person\/13bff4786a7357d4d8ef64c080647721\"},\"headline\":\"Comment r\u00e9ussir un transfert d\u2019activit\u00e9 dans votre entreprise ?\",\"datePublished\":\"2014-02-19T06:49:29+00:00\",\"dateModified\":\"2015-01-21T08:52:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/\"},\"wordCount\":957,\"publisher\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/tourbillon_11266243m-credit-principal-fotolia.com1_.jpg\",\"keywords\":[\"conduite du changement\",\"r\u00e9organisation\",\"transfert d\u2019activit\u00e9\",\"Transformation\"],\"articleSection\":[\"M\u00e9tiers - Strat\u00e9gie &amp; projets IT\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/\",\"url\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/\",\"name\":\"Comment r\u00e9ussir un transfert d\u2019activit\u00e9 dans votre entreprise ?\",\"isPartOf\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/tourbillon_11266243m-credit-principal-fotolia.com1_.jpg\",\"datePublished\":\"2014-02-19T06:49:29+00:00\",\"dateModified\":\"2015-01-21T08:52:57+00:00\",\"description\":\"Un transfert d\u2019activit\u00e9 d\u2019une \u00e9quipe \u00e0 une autre est souvent chronophage et long \u00e0 mettre en place\u2026 beaucoup trop en tous cas au regard des objectifs que s\u2019est fix\u00e9e l\u2019entreprise ! Clarifier la r\u00e9partition des activit\u00e9s et responsabilit\u00e9s entre directions ou encore homog\u00e9n\u00e9iser et industrialiser les pratiques\",\"breadcrumb\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#primaryimage\",\"url\":\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/tourbillon_11266243m-credit-principal-fotolia.com1_.jpg\",\"contentUrl\":\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/tourbillon_11266243m-credit-principal-fotolia.com1_.jpg\",\"width\":1194,\"height\":1592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.riskinsight-wavestone.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment r\u00e9ussir un transfert d\u2019activit\u00e9 dans votre entreprise ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#website\",\"url\":\"https:\/\/www.riskinsight-wavestone.com\/en\/\",\"name\":\"RiskInsight\",\"description\":\"The cybersecurity &amp; digital trust blog by Wavestone&#039;s consultants\",\"publisher\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.riskinsight-wavestone.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#organization\",\"name\":\"Wavestone\",\"url\":\"https:\/\/www.riskinsight-wavestone.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2021\/08\/Monogramme\u2013W\u2013NEGA-RGB-50x50-1.png\",\"contentUrl\":\"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2021\/08\/Monogramme\u2013W\u2013NEGA-RGB-50x50-1.png\",\"width\":50,\"height\":50,\"caption\":\"Wavestone\"},\"image\":{\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/person\/13bff4786a7357d4d8ef64c080647721\",\"name\":\"Emilie Molino\",\"url\":\"https:\/\/www.riskinsight-wavestone.com\/en\/author\/emilie-molino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment r\u00e9ussir un transfert d\u2019activit\u00e9 dans votre entreprise ?","description":"Un transfert d\u2019activit\u00e9 d\u2019une \u00e9quipe \u00e0 une autre est souvent chronophage et long \u00e0 mettre en place\u2026 beaucoup trop en tous cas au regard des objectifs que s\u2019est fix\u00e9e l\u2019entreprise ! Clarifier la r\u00e9partition des activit\u00e9s et responsabilit\u00e9s entre directions ou encore homog\u00e9n\u00e9iser et industrialiser les pratiques","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/","og_locale":"en_US","og_type":"article","og_title":"Comment r\u00e9ussir un transfert d\u2019activit\u00e9 dans votre entreprise ?","og_description":"Un transfert d\u2019activit\u00e9 d\u2019une \u00e9quipe \u00e0 une autre est souvent chronophage et long \u00e0 mettre en place\u2026 beaucoup trop en tous cas au regard des objectifs que s\u2019est fix\u00e9e l\u2019entreprise ! Clarifier la r\u00e9partition des activit\u00e9s et responsabilit\u00e9s entre directions ou encore homog\u00e9n\u00e9iser et industrialiser les pratiques","og_url":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/","og_site_name":"RiskInsight","article_published_time":"2014-02-19T06:49:29+00:00","article_modified_time":"2015-01-21T08:52:57+00:00","og_image":[{"width":1194,"height":1592,"url":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/tourbillon_11266243m-credit-principal-fotolia.com1_.jpg","type":"image\/jpeg"}],"author":"Emilie Molino, Carole Pezzali","twitter_misc":{"Written by":"Emilie Molino, Carole Pezzali","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#article","isPartOf":{"@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/"},"author":{"name":"Emilie Molino","@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/person\/13bff4786a7357d4d8ef64c080647721"},"headline":"Comment r\u00e9ussir un transfert d\u2019activit\u00e9 dans votre entreprise ?","datePublished":"2014-02-19T06:49:29+00:00","dateModified":"2015-01-21T08:52:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/"},"wordCount":957,"publisher":{"@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#organization"},"image":{"@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/tourbillon_11266243m-credit-principal-fotolia.com1_.jpg","keywords":["conduite du changement","r\u00e9organisation","transfert d\u2019activit\u00e9","Transformation"],"articleSection":["M\u00e9tiers - Strat\u00e9gie &amp; projets IT"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/","url":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/","name":"Comment r\u00e9ussir un transfert d\u2019activit\u00e9 dans votre entreprise ?","isPartOf":{"@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#primaryimage"},"image":{"@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/tourbillon_11266243m-credit-principal-fotolia.com1_.jpg","datePublished":"2014-02-19T06:49:29+00:00","dateModified":"2015-01-21T08:52:57+00:00","description":"Un transfert d\u2019activit\u00e9 d\u2019une \u00e9quipe \u00e0 une autre est souvent chronophage et long \u00e0 mettre en place\u2026 beaucoup trop en tous cas au regard des objectifs que s\u2019est fix\u00e9e l\u2019entreprise ! Clarifier la r\u00e9partition des activit\u00e9s et responsabilit\u00e9s entre directions ou encore homog\u00e9n\u00e9iser et industrialiser les pratiques","breadcrumb":{"@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#primaryimage","url":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/tourbillon_11266243m-credit-principal-fotolia.com1_.jpg","contentUrl":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2014\/02\/tourbillon_11266243m-credit-principal-fotolia.com1_.jpg","width":1194,"height":1592},{"@type":"BreadcrumbList","@id":"https:\/\/www.riskinsight-wavestone.com\/2014\/02\/comment-reussir-un-transfert-dactivite-dans-votre-entreprise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.riskinsight-wavestone.com\/en\/"},{"@type":"ListItem","position":2,"name":"Comment r\u00e9ussir un transfert d\u2019activit\u00e9 dans votre entreprise ?"}]},{"@type":"WebSite","@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#website","url":"https:\/\/www.riskinsight-wavestone.com\/en\/","name":"RiskInsight","description":"The cybersecurity &amp; digital trust blog by Wavestone&#039;s consultants","publisher":{"@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.riskinsight-wavestone.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#organization","name":"Wavestone","url":"https:\/\/www.riskinsight-wavestone.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2021\/08\/Monogramme\u2013W\u2013NEGA-RGB-50x50-1.png","contentUrl":"https:\/\/www.riskinsight-wavestone.com\/wp-content\/uploads\/2021\/08\/Monogramme\u2013W\u2013NEGA-RGB-50x50-1.png","width":50,"height":50,"caption":"Wavestone"},"image":{"@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.riskinsight-wavestone.com\/en\/#\/schema\/person\/13bff4786a7357d4d8ef64c080647721","name":"Emilie Molino","url":"https:\/\/www.riskinsight-wavestone.com\/en\/author\/emilie-molino\/"}]}},"_links":{"self":[{"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/posts\/5074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/comments?post=5074"}],"version-history":[{"count":12,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/posts\/5074\/revisions"}],"predecessor-version":[{"id":6187,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/posts\/5074\/revisions\/6187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/media\/6185"}],"wp:attachment":[{"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/media?parent=5074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/categories?post=5074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/tags?post=5074"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.riskinsight-wavestone.com\/en\/wp-json\/wp\/v2\/coauthors?post=5074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}